{"id":19259,"date":"2026-05-13T16:50:14","date_gmt":"2026-05-13T16:50:14","guid":{"rendered":"https:\/\/mitrerosario.com.ar\/inicio\/?p=19259"},"modified":"2026-05-13T16:50:14","modified_gmt":"2026-05-13T16:50:14","slug":"desalojaron-una-vivienda-de-zona-oeste-vinculada-al-excomisario-osvaldo-bejaran-condenado-por-enriquecimiento-ilicito","status":"publish","type":"post","link":"https:\/\/mitrerosario.com.ar\/inicio\/index.php\/2026\/05\/13\/desalojaron-una-vivienda-de-zona-oeste-vinculada-al-excomisario-osvaldo-bejaran-condenado-por-enriquecimiento-ilicito\/","title":{"rendered":"Desalojaron una vivienda de zona oeste vinculada al excomisario Osvaldo Bejar\u00e1n, condenado por enriquecimiento il\u00edcito"},"content":{"rendered":"\n<p>El Gobierno de Santa Fe avanz\u00f3 con el decomiso de una propiedad de la zona oeste de Rosario ligada a Osvaldo Ra\u00fal Bejar\u00e1n<strong>, excomisario condenado en 2021 por enriquecimiento il\u00edcito<\/strong>. Tras la ratificaci\u00f3n del fallo este a\u00f1o por parte de la Corte Suprema, se habilit\u00f3 el operativo y <strong>las personas que viv\u00edan en la casa fueron desalojadas.<\/strong><\/p>\n\n\n\n<p>La posesi\u00f3n del inmueble de dos pisos fue efectuada en un sector de calle <strong>Lavalle al 900<\/strong> por personal de la Agencia Provincial de Registro, Administraci\u00f3n y Destino de Bienes y Derechos Patrimoniales (Aprad). Estuvo presente el secretario de Gesti\u00f3n de Registros Provinciales, Mat\u00edas Figueroa Escauriza.<\/p>\n\n\n\n<p>En este marco, se confeccion\u00f3 un inventario de los bienes que se encontraban dentro del domicilio, entre los que figuraba <strong>una pistola con balas<\/strong>. En este caso, la situaci\u00f3n legal del arma de fuego qued\u00f3 sujeta a pericias, en las que se buscar\u00e1 determinar si el portador contaba con autorizaci\u00f3n legal para tenerla.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/rosarionuestrocdn.eleco.com.ar\/media\/2026\/05\/bejaran_arma.jpeg\" alt=\"bejar\u00e1n arma\"\/><\/figure>\n\n\n\n<p>Durante el procedimiento, Figueroa Escauriza anticip\u00f3 que \u201cel destino m\u00e1s probable\u201d para el inmueble ser\u00e1 un remate, aunque evaluar\u00e1n si puede ser reutilizada bajo las tareas de alg\u00fan organismo estatal.<\/p>\n\n\n\n<p>En cuanto a Bejar\u00e1n, el ex integrante de la polic\u00eda fue investigado durante m\u00e1s de una d\u00e9cada luego de cumplir funciones como jefe de Leyes Especiales, \u00e1rea encargada de la persecuci\u00f3n de delitos de juego clandestino en la ciudad. Lo condenaron tras comprobarse que hab\u00eda un desajuste entre sus bienes y sus ingresos, incluyendo la compra de seis veh\u00edculos, dos propiedades y una licencia de taxi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El operativo fue llevado a cabo por la Agencia Provincial de Registro, Administraci\u00f3n y Destino de Bienes y Derechos Patrimoniales (Aprad). Encontraron un arma de fuego en el lugar.<\/p>\n","protected":false},"author":2,"featured_media":19260,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-19259","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/mitrerosario.com.ar\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/19259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mitrerosario.com.ar\/inicio\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mitrerosario.com.ar\/inicio\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mitrerosario.com.ar\/inicio\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mitrerosario.com.ar\/inicio\/index.php\/wp-json\/wp\/v2\/comments?post=19259"}],"version-history":[{"count":1,"href":"https:\/\/mitrerosario.com.ar\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/19259\/revisions"}],"predecessor-version":[{"id":19261,"href":"https:\/\/mitrerosario.com.ar\/inicio\/index.php\/wp-json\/wp\/v2\/posts\/19259\/revisions\/19261"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mitrerosario.com.ar\/inicio\/index.php\/wp-json\/wp\/v2\/media\/19260"}],"wp:attachment":[{"href":"https:\/\/mitrerosario.com.ar\/inicio\/index.php\/wp-json\/wp\/v2\/media?parent=19259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mitrerosario.com.ar\/inicio\/index.php\/wp-json\/wp\/v2\/categories?post=19259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mitrerosario.com.ar\/inicio\/index.php\/wp-json\/wp\/v2\/tags?post=19259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}